{"id":1042,"date":"2018-08-31T16:27:11","date_gmt":"2018-08-31T19:27:11","guid":{"rendered":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/homologaciones-administracion\/"},"modified":"2021-05-27T09:15:48","modified_gmt":"2021-05-27T12:15:48","slug":"homologaciones-administracion","status":"publish","type":"page","link":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/homologaciones-administracion\/","title":{"rendered":"Homologaciones Administraci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"margin-left: auto; margin-right: auto;\" border=\"0\">\n<tbody>\n<tr>\n<td><span style=\"font-size: 12pt;\" data-mce-mark=\"1\"><img decoding=\"async\" title=\"Almanaque\" src=\"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-content\/uploads\/2018\/08\/almanaque.bmp\" alt=\"Almanaque\" border=\"0\" \/><\/span><\/td>\n<td>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #ff6600;\"><strong>28 de mayo de 2021<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18.6667px;\"><b>Finalizaci\u00f3n del plazo de entrega para los tr\u00e1mites de homologaciones<\/b><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-size: 12pt;\" data-mce-mark=\"1\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: 12pt;\" data-mce-mark=\"1\">Pasos para llevar a cabo las homologaciones:<\/span><\/p>\n<ol>\n<li><span style=\"font-size: 12pt;\" data-mce-mark=\"1\">Presentar en 1(un) folio la 1er. hoja de la siguiente ficha resumen del pedido de homologaci\u00f3n solicitada por el estudiante. Descargar y completar la<strong> <a title=\"Solicitud de Homologaci\u00f3n de Administraci\u00f3n RM 2090\/2015\" href=\"upload\/1-Solicitud_Alumno_Administracion_RM_2090-2015.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span data-mce-mark=\"1\">Solicitud de homologaciones resumen presentada por el estudiante<\/span><\/span><\/a><\/strong><span data-mce-mark=\"1\">.<\/span><\/span><\/li>\n<li><span style=\"font-size: 12pt;\" data-mce-mark=\"1\"> Presentar y completar 1(una) ficha de homologaci\u00f3n por materia. Con dicha ficha se adjunta el programa debidamente sellado, firmado y con nota por la autoridad de la instituci\u00f3n de la que proviene. Descargar y completar la<span data-mce-mark=\"1\"><strong> <a title=\"Solicitud de Homologaci\u00f3n de materias de Administraci\u00f3n RM 2090\/2015\" href=\"upload\/2-Asignaturas_homologadas_Administracion_RM_2090-2015.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Solicitud de Homologaci\u00f3n de materias de\u00a0Administraci\u00f3n RM 2090\/2015<\/span><\/a><\/strong><\/span>. <strong><span style=\"color: #ff6600;\">Atenci\u00f3n!!!<\/span><\/strong> s\u00f3lo completar la 1ra parte de la ficha.<\/span><\/li>\n<li><span style=\"font-size: 12pt;\">Presentar la ficha vac\u00eda de la <a title=\"Disposici\u00f3n de Homologaci\u00f3n de Administraci\u00f3n RM 2090\/2015\" href=\"upload\/3-Disposicion_homologaciones_Administracion_RM_2090-2015.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Disposici\u00f3n de Homologaci\u00f3n de Administraci\u00f3n RM 2090\/2015<\/strong><\/span><\/a>.<\/span><\/li>\n<li><span style=\"color: #ff6600;\"><strong><span style=\"font-size: 12pt;\">Completar todo y entregar a la brevedad.<\/span><\/strong><\/span><\/li>\n<\/ol>\n<p><span style=\"font-size: 12pt;\" data-mce-mark=\"1\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; 28 de mayo de 2021 Finalizaci\u00f3n del plazo de entrega para los tr\u00e1mites de homologaciones \u00a0 Pasos para llevar a cabo las homologaciones: Presentar en 1(un) folio la 1er. hoja de la siguiente ficha resumen del pedido de homologaci\u00f3n solicitada por el estudiante. Descargar y completar la Solicitud de homologaciones resumen presentada por el &#8230; <a title=\"Homologaciones Administraci\u00f3n\" class=\"read-more\" href=\"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/homologaciones-administracion\/\" aria-label=\"More on Homologaciones Administraci\u00f3n\">[+]<\/a><\/p>\n","protected":false},"author":100,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/1042"}],"collection":[{"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":3,"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/1042\/revisions"}],"predecessor-version":[{"id":1792,"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/1042\/revisions\/1792"}],"wp:attachment":[{"href":"https:\/\/isp22-sfe.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}